{"id":196643,"date":"2026-03-21T14:32:26","date_gmt":"2026-03-21T14:32:26","guid":{"rendered":""},"modified":"2026-03-21T14:32:26","modified_gmt":"2026-03-21T14:32:26","slug":"%e7%b5%8c%e6%b8%88%e7%94%a3%e6%a5%ad%e7%9c%81%ef%bc%9a%e3%80%8cit%e5%b0%8e%e5%85%a5%e8%a3%9c%e5%8a%a9%e9%87%91-%e4%bd%8e%e6%84%9f%e6%9f%93%e3%83%aa%e3%82%b9%e3%82%af%e5%9e%8b%e3%83%93%e3%82%b8","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e7%b5%8c%e6%b8%88%e7%94%a3%e6%a5%ad%e7%9c%81%ef%bc%9a%e3%80%8cit%e5%b0%8e%e5%85%a5%e8%a3%9c%e5%8a%a9%e9%87%91-%e4%bd%8e%e6%84%9f%e6%9f%93%e3%83%aa%e3%82%b9%e3%82%af%e5%9e%8b%e3%83%93%e3%82%b8\/","title":{"rendered":"\u7d4c\u6e08\u7523\u696d\u7701\uff1a\u300cIT\u5c0e\u5165\u88dc\u52a9\u91d1 \u4f4e\u611f\u67d3\u30ea\u30b9\u30af\u578b\u30d3\u30b8\u30cd\u30b9\u67a0(\u7279\u5225\u67a0C&#8230;"},"content":{"rendered":"<p>\u30dd\u30b9\u30c8\u30b3\u30ed\u30ca\u306e\u72b6\u6cc1\u306b\u5bfe\u5fdc\u3059\u308b\u305f\u3081\u3001\u696d\u52d9\u306e\u975e\u5bfe\u9762\u5316\u3084\u30c6\u30ec\u30ef\u30fc\u30af\u5316\u306b\u5fc5\u8981\u3068\u306a\u308bIT \u30c4\u30fc\u30eb\u3092\u5c0e\u5165\u3059\u308b\u969b\u306b\u306f\u3001\u9ad8\u3044\u88dc\u52a9\u7387\u3067\u306e\u652f\u63f4\u3092\u53d7\u3051\u308b\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3010\u7279\u5225\u67a0\u3011\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-196643","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/196643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=196643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}