{"id":196562,"date":"2026-03-21T14:32:24","date_gmt":"2026-03-21T14:32:24","guid":{"rendered":""},"modified":"2026-03-21T14:32:24","modified_gmt":"2026-03-21T14:32:24","slug":"%e5%85%a8%e5%9b%bd%e4%bf%a1%e7%94%a8%e4%bf%9d%e8%a8%bc%e5%8d%94%e4%bc%9a%e9%80%a3%e5%90%88%e4%bc%9a%ef%bc%9a%e3%80%8c%e7%b5%8c%e5%96%b6%e6%89%bf%e7%b6%99%e9%96%a2%e9%80%a3%e4%bf%9d%e8%a8%bc%e3%80%8d","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e5%85%a8%e5%9b%bd%e4%bf%a1%e7%94%a8%e4%bf%9d%e8%a8%bc%e5%8d%94%e4%bc%9a%e9%80%a3%e5%90%88%e4%bc%9a%ef%bc%9a%e3%80%8c%e7%b5%8c%e5%96%b6%e6%89%bf%e7%b6%99%e9%96%a2%e9%80%a3%e4%bf%9d%e8%a8%bc%e3%80%8d\/","title":{"rendered":"\u5168\u56fd\u4fe1\u7528\u4fdd\u8a3c\u5354\u4f1a\u9023\u5408\u4f1a\uff1a\u300c\u7d4c\u55b6\u627f\u7d99\u95a2\u9023\u4fdd\u8a3c\u300d"},"content":{"rendered":"<p>\u4e2d\u5c0f\u4f01\u696d\u8005\u304c\u7d4c\u55b6\u306e\u627f\u7d99\u6642\u306b\u5fc5\u8981\u3068\u3059\u308b\u8cc7\u91d1(\u682a\u5f0f\u53d6\u5f97\u8cc7\u91d1\u7b49)\u3092\u91d1\u878d\u6a5f\u95a2\u304b\u3089\u501f\u308a\u5165\u308c\u308b\u5834\u5408\u306b\u3001\u4fe1\u7528\u4fdd\u8a3c\u5354\u4f1a\u304c\u4fdd\u8a3c\u3092\u884c\u3046\u3053\u3068\u3067\u3001\u7d4c\u55b6\u306e\u627f\u7d99\u306e\u5186\u6ed1\u5316\u3092\u56f3\u308a\u307e\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-196562","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/196562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=196562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}