{"id":196519,"date":"2026-03-21T14:32:23","date_gmt":"2026-03-21T14:32:23","guid":{"rendered":""},"modified":"2026-03-21T14:32:23","modified_gmt":"2026-03-21T14:32:23","slug":"%e5%9b%bd%e7%a8%8e%e5%ba%81%e3%80%81%e5%9b%bd%e7%a8%8e%e5%b1%80%ef%bc%9a%e3%80%8c%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e8%80%85%e7%ad%89%e3%81%ae%e6%b3%95%e4%ba%ba%e7%a8%8e%e7%8e%87%e3%81%ae%e7%89%b9","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e5%9b%bd%e7%a8%8e%e5%ba%81%e3%80%81%e5%9b%bd%e7%a8%8e%e5%b1%80%ef%bc%9a%e3%80%8c%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%ad%e8%80%85%e7%ad%89%e3%81%ae%e6%b3%95%e4%ba%ba%e7%a8%8e%e7%8e%87%e3%81%ae%e7%89%b9\/","title":{"rendered":"\u56fd\u7a0e\u5e81\u3001\u56fd\u7a0e\u5c40\uff1a\u300c\u4e2d\u5c0f\u4f01\u696d\u8005\u7b49\u306e\u6cd5\u4eba\u7a0e\u7387\u306e\u7279\u4f8b\u300d"},"content":{"rendered":"<p>\u4e2d\u5c0f\u4f01\u696d\u7b49\u306e\u6cd5\u4eba\u7a0e\u7387\u306f\u8efd\u6e1b\u3055\u308c\u307e\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-196519","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/196519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=196519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}