{"id":164548,"date":"2026-03-21T14:22:55","date_gmt":"2026-03-21T14:22:55","guid":{"rendered":""},"modified":"2026-03-21T14:22:55","modified_gmt":"2026-03-21T14:22:55","slug":"%e7%a5%9e%e5%a5%88%e5%b7%9d%e7%9c%8c%e6%a8%aa%e9%a0%88%e8%b3%80%e5%b8%82%ef%bc%9a%e3%80%8c%e3%82%bb%e3%82%ad%e3%83%a5%e3%83%aa%e3%83%86%e3%82%a3%e6%94%af%e6%8f%b4%e8%a3%9c%e5%8a%a9%e9%87%91%e3%80%8d","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e7%9c%8c%e6%a8%aa%e9%a0%88%e8%b3%80%e5%b8%82%ef%bc%9a%e3%80%8c%e3%82%bb%e3%82%ad%e3%83%a5%e3%83%aa%e3%83%86%e3%82%a3%e6%94%af%e6%8f%b4%e8%a3%9c%e5%8a%a9%e9%87%91%e3%80%8d\/","title":{"rendered":"\u795e\u5948\u5ddd\u770c\u6a2a\u9808\u8cc0\u5e02\uff1a\u300c\u30bb\u30ad\u30e5\u30ea\u30c6\u30a3\u652f\u63f4\u88dc\u52a9\u91d1\u300d"},"content":{"rendered":"<p>\u6a2a\u9808\u8cc0\u5546\u5de5\u4f1a\u8b70\u6240\u304c\u5b9f\u65bd\u3059\u308b\u300cYOKOSUKA\u60c5\u5831\u30bb\u30ad\u30e5\u30ea\u30c6\u30a3\u30d7\u30ed\u30b8\u30a7\u30af\u30c8\u300d\u304c\u63a8\u5968\u3059\u308b\u7aef\u672b\u76e3\u8996\u30b5\u30fc\u30d3\u30b9\u3010\u304a\u52a9\u3051\u4f8d\u3011\u5c0e\u5165\u4e8b\u696d\u8005\u306b\u5bfe\u3057\u3066\u3001\u30bb\u30ad\u30e5\u30ea\u30c6\u30a3\u30c4\u30fc\u30eb\u5c0e\u5165\u3084\u5229\u7528\u7d4c\u8cbb\u306e\u4e00\u90e8\u3092\u88dc\u52a9\u3057\u307e\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-164548","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/164548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=164548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}