{"id":164484,"date":"2026-03-21T14:22:53","date_gmt":"2026-03-21T14:22:53","guid":{"rendered":""},"modified":"2026-03-21T14:22:53","modified_gmt":"2026-03-21T14:22:53","slug":"%e5%8c%97%e6%b5%b7%e9%81%93%e6%a8%99%e8%8c%b6%e7%94%ba%ef%bc%9a%e3%80%8c%e6%a8%99%e8%8c%b6%e7%94%bagogo%e3%83%81%e3%83%a3%e3%83%ac%e3%83%b3%e3%82%b8%e6%94%af%e6%8f%b4%e4%ba%8b%e6%a5%ad%e8%a3%9c","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e5%8c%97%e6%b5%b7%e9%81%93%e6%a8%99%e8%8c%b6%e7%94%ba%ef%bc%9a%e3%80%8c%e6%a8%99%e8%8c%b6%e7%94%bagogo%e3%83%81%e3%83%a3%e3%83%ac%e3%83%b3%e3%82%b8%e6%94%af%e6%8f%b4%e4%ba%8b%e6%a5%ad%e8%a3%9c\/","title":{"rendered":"\u5317\u6d77\u9053\u6a19\u8336\u753a\uff1a\u300c\u6a19\u8336\u753aGOGO\u30c1\u30e3\u30ec\u30f3\u30b8\u652f\u63f4\u4e8b\u696d\u88dc\u52a9\u91d1\u300d"},"content":{"rendered":"<p>\u672c\u753a\u306b\u304a\u3051\u308b\u5730\u57df\u7d4c\u6e08\u306e\u6d3b\u6027\u5316\u306b\u8cc7\u3059\u308b\u305f\u3081\u3001\u65b0\u898f\u4e8b\u696d\u30c1\u30e3\u30ec\u30f3\u30b8\u306e\u30b5\u30dd\u30fc\u30c8\u3084\u753a\u5185\u4e8b\u696d\u8005\u306b\u304a\u3051\u308b\u516c\u76ca\u6027\u3092\u6301\u3063\u305f\u672c\u753a\u306e\u9b45\u529b\u30fb\u8a8d\u77e5\u5ea6\u5411\u4e0a\u53ca\u3073\u4ed8\u52a0\u4fa1\u5024\u5411\u4e0a\u306e\u53d6\u7d44\u306e\u652f\u63f4\u3092\u884c\u3044\u307e\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-164484","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/164484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=164484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}