{"id":164006,"date":"2026-03-21T14:22:44","date_gmt":"2026-03-21T14:22:44","guid":{"rendered":""},"modified":"2026-03-21T14:22:44","modified_gmt":"2026-03-21T14:22:44","slug":"%e5%b2%a1%e5%b1%b1%e7%9c%8c%e7%be%8e%e5%92%b2%e7%94%ba%ef%bc%9a%e3%80%8c%e7%be%8e%e5%92%b2%e7%94%ba%e6%9e%97%e6%a5%ad%e8%b3%87%e6%a0%bc%e7%ad%89%e5%8f%96%e5%be%97%e8%b2%bb%e6%94%af%e6%8f%b4%e4%ba%8b","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e5%b2%a1%e5%b1%b1%e7%9c%8c%e7%be%8e%e5%92%b2%e7%94%ba%ef%bc%9a%e3%80%8c%e7%be%8e%e5%92%b2%e7%94%ba%e6%9e%97%e6%a5%ad%e8%b3%87%e6%a0%bc%e7%ad%89%e5%8f%96%e5%be%97%e8%b2%bb%e6%94%af%e6%8f%b4%e4%ba%8b\/","title":{"rendered":"\u5ca1\u5c71\u770c\u7f8e\u54b2\u753a\uff1a\u300c\u7f8e\u54b2\u753a\u6797\u696d\u8cc7\u683c\u7b49\u53d6\u5f97\u8cbb\u652f\u63f4\u4e8b\u696d\u88dc\u52a9\u91d1\u300d"},"content":{"rendered":"<p>\u6797\u696d\u306b\u5fc5\u8981\u306a\u8cc7\u683c\u7b49\u306e\u53d6\u5f97\u3092\u5e0c\u671b\u3059\u308b\u65b9\u3092\u5bfe\u8c61\u306b\u300e\u7f8e\u54b2\u753a\u6797\u696d\u8cc7\u683c\u7b49\u53d6\u5f97\u652f\u63f4\u4e8b\u696d\u88dc\u52a9\u91d1\u300f\u3092\u4ee4\u548c7\u5e74\u5ea6\u3088\u308a\u5275\u8a2d\u3057\u307e\u3057\u305f\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-164006","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/164006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=164006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}