{"id":162248,"date":"2026-03-21T14:22:08","date_gmt":"2026-03-21T14:22:08","guid":{"rendered":""},"modified":"2026-03-21T14:22:08","modified_gmt":"2026-03-21T14:22:08","slug":"%e3%80%8c%e7%89%b9%e5%ae%9a%e6%b1%82%e8%81%b7%e8%80%85%e9%9b%87%e7%94%a8%e9%96%8b%e7%99%ba%e5%8a%a9%e6%88%90%e9%87%91%ef%bc%88%e7%89%b9%e5%ae%9a%e5%b0%b1%e8%81%b7%e5%9b%b0%e9%9b%a3%e8%80%85%e3%82%b3","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e3%80%8c%e7%89%b9%e5%ae%9a%e6%b1%82%e8%81%b7%e8%80%85%e9%9b%87%e7%94%a8%e9%96%8b%e7%99%ba%e5%8a%a9%e6%88%90%e9%87%91%ef%bc%88%e7%89%b9%e5%ae%9a%e5%b0%b1%e8%81%b7%e5%9b%b0%e9%9b%a3%e8%80%85%e3%82%b3\/","title":{"rendered":"\u300c\u7279\u5b9a\u6c42\u8077\u8005\u96c7\u7528\u958b\u767a\u52a9\u6210\u91d1\uff08\u7279\u5b9a\u5c31\u8077\u56f0\u96e3\u8005\u30b3\u30fc\u30b9\uff09\u300d\uff08\u4ee4\u548c7\u5e74\u5ea6&#8230;"},"content":{"rendered":"<p>\u9ad8\u5e74\u9f62\u8005\u3084\u969c\u5bb3\u8005\u7b49\u306e\u5c31\u8077\u56f0\u96e3\u8005\u3092\u30cf\u30ed\u30fc\u30ef\u30fc\u30af\u7b49\u306e\u7d39\u4ecb\u306b\u3088\u308a\u3001\u7d99\u7d9a\u3057\u3066\u96c7\u7528\u3059\u308b\u52b4\u50cd\u8005\u3068\u3057\u3066\u96c7\u3044\u5165\u308c\u308b\u4e8b\u696d\u4e3b\u306b\u5bfe\u3057\u3066\u52a9\u6210\u3055\u308c\u307e\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-162248","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/162248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=162248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}