{"id":160926,"date":"2026-03-21T14:21:38","date_gmt":"2026-03-21T14:21:38","guid":{"rendered":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e6%9d%b1%e4%ba%ac%e9%83%bd%ef%bc%9a%e3%80%8cev%e3%83%90%e3%82%b9%e3%83%bbev%e3%83%88%e3%83%a9%e3%83%83%e3%82%af%e5%b0%8e%e5%85%a5%e4%bf%83%e9%80%b2%e4%ba%8b%e6%a5%ad%e3%80%8d\/"},"modified":"2026-03-21T14:21:38","modified_gmt":"2026-03-21T14:21:38","slug":"%e6%9d%b1%e4%ba%ac%e9%83%bd%ef%bc%9a%e3%80%8cev%e3%83%90%e3%82%b9%e3%83%bbev%e3%83%88%e3%83%a9%e3%83%83%e3%82%af%e5%b0%8e%e5%85%a5%e4%bf%83%e9%80%b2%e4%ba%8b%e6%a5%ad%e3%80%8d","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e6%9d%b1%e4%ba%ac%e9%83%bd%ef%bc%9a%e3%80%8cev%e3%83%90%e3%82%b9%e3%83%bbev%e3%83%88%e3%83%a9%e3%83%83%e3%82%af%e5%b0%8e%e5%85%a5%e4%bf%83%e9%80%b2%e4%ba%8b%e6%a5%ad%e3%80%8d\/","title":{"rendered":"\u6771\u4eac\u90fd\uff1a\u300cEV\u30d0\u30b9\u30fbEV\u30c8\u30e9\u30c3\u30af\u5c0e\u5165\u4fc3\u9032\u4e8b\u696d\u300d"},"content":{"rendered":"<p>\u81ea\u52d5\u8eca\u304b\u3089\u6392\u51fa\u3055\u308c\u308b\u4e8c\u9178\u5316\u70ad\u7d20\u7b49\u306e\u524a\u6e1b\u3092\u56f3\u308b\u305f\u3081\u3001\u516c\u76ca\u8ca1\u56e3\u6cd5\u4eba\u6771\u4eac\u90fd\u74b0\u5883\u516c\u793e\u304c\u3001EV\u30d0\u30b9\u3001PHE\uff36\u30d0\u30b9\u3001EV\u30c8\u30e9\u30c3\u30af\u53ca\u3073PHEV\u30c8\u30e9\u30c3\u30af\u3092\u5c0e\u5165\u3059\u308b\u8005\u306b\u5bfe\u3057\u3001\u305d\u306e\u7d4c\u8cbb\u306e\u4e00\u90e8\u3092\u52a9\u6210\u3059\u308b\u3082\u306e\u3067\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-160926","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/160926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=160926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}