{"id":159328,"date":"2026-03-21T14:21:05","date_gmt":"2026-03-21T14:21:05","guid":{"rendered":""},"modified":"2026-03-21T14:21:05","modified_gmt":"2026-03-21T14:21:05","slug":"%e5%b2%a9%e6%89%8b%e7%9c%8c%e5%ae%ae%e5%8f%a4%e5%b8%82%ef%bc%9a%e3%80%8c%e4%bb%a4%e5%92%8c7%e5%b9%b4%e5%ba%a6%e5%ae%ae%e5%8f%a4%e5%b8%82%e4%bd%8f%e5%ae%85%e6%96%ad%e7%86%b1%e3%83%aa%e3%83%95%e3%82%a9","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e5%b2%a9%e6%89%8b%e7%9c%8c%e5%ae%ae%e5%8f%a4%e5%b8%82%ef%bc%9a%e3%80%8c%e4%bb%a4%e5%92%8c7%e5%b9%b4%e5%ba%a6%e5%ae%ae%e5%8f%a4%e5%b8%82%e4%bd%8f%e5%ae%85%e6%96%ad%e7%86%b1%e3%83%aa%e3%83%95%e3%82%a9\/","title":{"rendered":"\u5ca9\u624b\u770c\u5bae\u53e4\u5e02\uff1a\u300c\u4ee4\u548c7\u5e74\u5ea6\u5bae\u53e4\u5e02\u4f4f\u5b85\u65ad\u71b1\u30ea\u30d5\u30a9\u30fc\u30e0\u63a8\u9032\u4e8b\u696d\u8cbb\u88dc\u52a9&#8230;"},"content":{"rendered":"<p>\u3054\u81ea\u5b85\u306e\u65ad\u71b1\u30ea\u30d5\u30a9\u30fc\u30e0\u3067\u7701\u30a8\u30cd\u5316\u306b\u3088\u308aCO2\u6392\u51fa\u91cf\u3092\u524a\u6e1b\u3059\u308b\u305f\u3081\u3001\u56fd\u306e\u88dc\u52a9\u91d1\u3092\u5229\u7528\u3057\u3066\u65ad\u71b1\u30ea\u30d5\u30a9\u30fc\u30e0\u3092\u3057\u305f\u65b9\u3078\u8cbb\u7528\u306e\u4e00\u90e8\u3092\u88dc\u52a9\u3057\u307e\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-159328","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/159328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=159328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}