{"id":156947,"date":"2026-03-21T14:20:11","date_gmt":"2026-03-21T14:20:11","guid":{"rendered":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e3%80%8c%e4%bc%81%e6%a5%ad%e8%aa%98%e8%87%b4%e8%a3%9c%e5%8a%a9%e9%87%91%e3%80%8d\/"},"modified":"2026-03-21T14:20:11","modified_gmt":"2026-03-21T14:20:11","slug":"%e3%80%8c%e4%bc%81%e6%a5%ad%e8%aa%98%e8%87%b4%e8%a3%9c%e5%8a%a9%e9%87%91%e3%80%8d","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e3%80%8c%e4%bc%81%e6%a5%ad%e8%aa%98%e8%87%b4%e8%a3%9c%e5%8a%a9%e9%87%91%e3%80%8d\/","title":{"rendered":"\u300c\u4f01\u696d\u8a98\u81f4\u88dc\u52a9\u91d1\u300d"},"content":{"rendered":"<p>\u5e02\u3067\u306f\u3001\u5e02\u5185\u3078\u306e\u4f01\u696d\u306e\u7acb\u5730\u3092\u4fc3\u9032\u3057\u3001\u7523\u696d\u632f\u8208\u304a\u3088\u3073\u96c7\u7528\u6a5f\u4f1a\u306e\u62e1\u5927\u3092\u76ee\u7684\u3068\u3057\u3066\u4f01\u696d\u8a98\u81f4\u88dc\u52a9\u91d1\u5236\u5ea6\u3092\u8a2d\u3051\u3066\u3044\u307e\u3059\u3002\u203b\u8a08\u753b\u7b49\u3054\u3056\u3044\u307e\u3057\u305f\u3089\u3054\u76f8\u8ac7\u304f\u3060\u3055\u3044\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-156947","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/156947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=156947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}