{"id":156424,"date":"2026-03-21T14:19:58","date_gmt":"2026-03-21T14:19:58","guid":{"rendered":""},"modified":"2026-03-21T14:19:58","modified_gmt":"2026-03-21T14:19:58","slug":"%e5%a4%a7%e5%88%86%e7%9c%8c%ef%bc%9a%e3%80%8c%e3%82%b0%e3%83%aa%e3%83%bc%e3%83%b3%e3%83%bb%e3%82%b3%e3%83%b3%e3%83%93%e3%83%8a%e3%83%bc%e3%83%88%e3%81%8a%e3%81%8a%e3%81%84%e3%81%9f%e5%89%b5%e5%87%ba","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e5%a4%a7%e5%88%86%e7%9c%8c%ef%bc%9a%e3%80%8c%e3%82%b0%e3%83%aa%e3%83%bc%e3%83%b3%e3%83%bb%e3%82%b3%e3%83%b3%e3%83%93%e3%83%8a%e3%83%bc%e3%83%88%e3%81%8a%e3%81%8a%e3%81%84%e3%81%9f%e5%89%b5%e5%87%ba\/","title":{"rendered":"\u5927\u5206\u770c\uff1a\u300c\u30b0\u30ea\u30fc\u30f3\u30fb\u30b3\u30f3\u30d3\u30ca\u30fc\u30c8\u304a\u304a\u3044\u305f\u5275\u51fa\u4e8b\u696d\u8cbb\u88dc\u52a9\u91d1\uff08\u56fd\u88dc\u52a9&#8230;"},"content":{"rendered":"<p>\u770c\u3067\u306f\u30012030\u5e74\u30012050\u5e74\u3092\u898b\u636e\u3048\u305f\u5927\u5206\u30b3\u30f3\u30d3\u30ca\u30fc\u30c8\u306e\u30ab\u30fc\u30dc\u30f3\u30cb\u30e5\u30fc\u30c8\u30e9\u30eb\u3068\u6301\u7d9a\u7684\u6210\u9577\u306e\u4e21\u7acb\u306b\u5411\u3051\u3066\u7523\u5b66\u5b98\u3067\u53d6\u308a\u307e\u3068\u3081\u305f\u300c\u30b0\u30ea\u30fc\u30f3\u30fb\u30b3\u30f3\u30d3\u30ca\u30fc\u30c8\u304a\u304a\u3044\u305f\u63a8\u9032\u69cb\u60f3\u300d\u306e\u5b9f\u73fe\u3092\u56f3\u308b\u305f\u3081\u3001\u4e8b\u696d\u5b9f\u65bd\u4e3b\u4f53\u304c\u884c\u3046CO2\u5206\u96e2\u30fb\u56de\u53ce\u30fb\u5229\u6d3b\u7528\u30fb\u8caf\u7559\u6280\u8853\u3084\u6c34&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-156424","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/156424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=156424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}