{"id":156201,"date":"2026-03-21T14:19:53","date_gmt":"2026-03-21T14:19:53","guid":{"rendered":""},"modified":"2026-03-21T14:19:53","modified_gmt":"2026-03-21T14:19:53","slug":"%e5%9f%bc%e7%8e%89%e7%9c%8c%e7%a7%a9%e7%88%b6%e5%b8%82%ef%bc%9a%e3%80%8c%e7%a7%a9%e7%88%b6%e5%b8%82%e4%bc%81%e6%a5%ad%e7%ab%b6%e4%ba%89%e5%8a%9b%e5%bc%b7%e5%8c%96%e6%94%af%e6%8f%b4%e4%ba%8b%e6%a5%ad-3","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e5%9f%bc%e7%8e%89%e7%9c%8c%e7%a7%a9%e7%88%b6%e5%b8%82%ef%bc%9a%e3%80%8c%e7%a7%a9%e7%88%b6%e5%b8%82%e4%bc%81%e6%a5%ad%e7%ab%b6%e4%ba%89%e5%8a%9b%e5%bc%b7%e5%8c%96%e6%94%af%e6%8f%b4%e4%ba%8b%e6%a5%ad-3\/","title":{"rendered":"\u57fc\u7389\u770c\u79e9\u7236\u5e02\uff1a\u300c\u79e9\u7236\u5e02\u4f01\u696d\u7af6\u4e89\u529b\u5f37\u5316\u652f\u63f4\u4e8b\u696d\u88dc\u52a9\u91d1\uff08BCP\u7b56\u5b9a\u652f&#8230;"},"content":{"rendered":"<p>\u5e02\u3067\u306f\u3001BCP\u3092\u5c02\u9580\u5bb6\u306e\u652f\u63f4\u3092\u53d7\u3051\u3066\u65b0\u898f\u306b\u7b56\u5b9a\u3059\u308b\u4e8b\u696d\u8005\u306b\u5bfe\u3057\u3001\u88dc\u52a9\u91d1\u3092\u4ea4\u4ed8\u3057\u3066\u3044\u307e\u3059\u3002\u203b\u4ea4\u4ed8\u624b\u7d9a\u3092\u5186\u6ed1\u306b\u9032\u3081\u308b\u305f\u3081\u3001\u7533\u8acb\u524d\u306b\u3001\u3042\u3089\u304b\u3058\u3081\u3054\u76f8\u8ac7\u304f\u3060\u3055\u3044\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-156201","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/156201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=156201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}