{"id":156159,"date":"2026-03-21T14:19:51","date_gmt":"2026-03-21T14:19:51","guid":{"rendered":""},"modified":"2026-03-21T14:19:51","modified_gmt":"2026-03-21T14:19:51","slug":"%e6%9d%b1%e4%ba%ac%e9%83%bd%ef%bc%9a%e3%80%8c%e4%bc%81%e6%a5%ad%e3%81%ae%e8%84%b1%e7%82%ad%e7%b4%a0%e7%b5%8c%e5%96%b6%e3%81%ab%e5%90%91%e3%81%91%e3%81%9f%e8%a8%88%e7%94%bb%e7%ad%96%e5%ae%9a%e6%94%af","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e6%9d%b1%e4%ba%ac%e9%83%bd%ef%bc%9a%e3%80%8c%e4%bc%81%e6%a5%ad%e3%81%ae%e8%84%b1%e7%82%ad%e7%b4%a0%e7%b5%8c%e5%96%b6%e3%81%ab%e5%90%91%e3%81%91%e3%81%9f%e8%a8%88%e7%94%bb%e7%ad%96%e5%ae%9a%e6%94%af\/","title":{"rendered":"\u6771\u4eac\u90fd\uff1a\u300c\u4f01\u696d\u306e\u8131\u70ad\u7d20\u7d4c\u55b6\u306b\u5411\u3051\u305f\u8a08\u753b\u7b56\u5b9a\u652f\u63f4\u4e8b\u696d\uff08SBT\u8a8d\u5b9a\u306e&#8230;"},"content":{"rendered":"<p>\u4f01\u696d\u304c\u8131\u70ad\u7d20\u5316\u306b\u5411\u3051\u3001CO2\u6392\u51fa\u91cf\u524a\u6e1b\u306e\u53d6\u7d44\u3092\u9032\u3081\u3066\u3044\u304f\u305f\u3081\u306b\u306f\u3001\u4f01\u696d\u3068\u3057\u3066\u4e2d\u9577\u671f\u7684\u306a\u524a\u6e1b\u76ee\u6a19\u3092\u9069\u5207\u306b\u8a2d\u5b9a\u3059\u308b\u3053\u3068\u304c\u91cd\u8981\u3067\u3059\u3002\u305d\u3053\u3067\u3001CO2\u524a\u6e1b\u76ee\u6a19\u306e\u8a8d\u5b9a\u306e\u53d6\u5f97\u306b\u5411\u3051\u305f\u652f\u63f4\u3092\u5b9f\u65bd\u3059\u308b\u3053\u3068\u3067\u3001\u5404\u4f01\u696d\u306e\u8131\u70ad\u7d20\u5316\u306b\u5411\u3051\u305f\u74b0\u5883\u6574\u5099\u306e\u53d6\u7d44\u3092\u5f8c\u62bc\u3057\u3057\u3066&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-156159","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/156159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=156159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}