{"id":154690,"date":"2026-03-21T14:19:21","date_gmt":"2026-03-21T14:19:21","guid":{"rendered":""},"modified":"2026-03-21T14:19:21","modified_gmt":"2026-03-21T14:19:21","slug":"%e7%a5%9e%e5%a5%88%e5%b7%9d%e7%9c%8c%e6%a8%aa%e9%a0%88%e8%b3%80%e5%b8%82%ef%bc%9a%e3%80%8c%e4%bc%81%e6%a5%adpr%e8%a3%9c%e5%8a%a9%e9%87%91%e3%80%8d%ef%bc%88%e4%bb%a4%e5%92%8c7%e5%b9%b4%e5%ba%a6","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e7%9c%8c%e6%a8%aa%e9%a0%88%e8%b3%80%e5%b8%82%ef%bc%9a%e3%80%8c%e4%bc%81%e6%a5%adpr%e8%a3%9c%e5%8a%a9%e9%87%91%e3%80%8d%ef%bc%88%e4%bb%a4%e5%92%8c7%e5%b9%b4%e5%ba%a6\/","title":{"rendered":"\u795e\u5948\u5ddd\u770c\u6a2a\u9808\u8cc0\u5e02\uff1a\u300c\u4f01\u696dPR\u88dc\u52a9\u91d1\u300d\uff08\u4ee4\u548c7\u5e74\u5ea6\uff09"},"content":{"rendered":"<p>\u4f01\u696d\u53ca\u3073\u88fd\u54c1\u3092PR\u3057\u3001\u30d3\u30b8\u30cd\u30b9\u30c1\u30e3\u30f3\u30b9\u3092\u62e1\u5927\u3059\u308b\u305f\u3081\u306e\u300e\u7523\u696d\u898b\u672c\u5e02\u3078\u306e\u51fa\u5c55\u300f\u3084\u300e\u4f01\u696d\u30d1\u30f3\u30d5\u30ec\u30c3\u30c8\u30fb\u30db\u30fc\u30e0\u30da\u30fc\u30b8\u306e\u4f5c\u6210\u300f\u300e\u4f01\u696dPR\u52d5\u753b\u306e\u4f5c\u6210\u300f\u7b49\u306b\u8981\u3059\u308b\u7d4c\u8cbb\u306e\u4e00\u90e8\u3092\u88dc\u52a9\u3057\u307e\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-154690","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/154690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=154690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}