{"id":153728,"date":"2026-03-21T14:19:02","date_gmt":"2026-03-21T14:19:02","guid":{"rendered":""},"modified":"2026-03-21T14:19:02","modified_gmt":"2026-03-21T14:19:02","slug":"%e7%a5%9e%e5%a5%88%e5%b7%9d%e7%9c%8c%e9%96%8b%e6%88%90%e7%94%ba%ef%bc%9a%e3%80%8c%e9%96%8b%e6%88%90%e7%94%ba%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%adgx%e6%88%a6%e7%95%a5%e4%ba%8b%e6%a5%ad%e5%88%a9%e5%ad%90","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e7%9c%8c%e9%96%8b%e6%88%90%e7%94%ba%ef%bc%9a%e3%80%8c%e9%96%8b%e6%88%90%e7%94%ba%e4%b8%ad%e5%b0%8f%e4%bc%81%e6%a5%adgx%e6%88%a6%e7%95%a5%e4%ba%8b%e6%a5%ad%e5%88%a9%e5%ad%90\/","title":{"rendered":"\u795e\u5948\u5ddd\u770c\u958b\u6210\u753a\uff1a\u300c\u958b\u6210\u753a\u4e2d\u5c0f\u4f01\u696dGX\u6226\u7565\u4e8b\u696d\u5229\u5b50\u88dc\u7d66\u5236\u5ea6\u300d\uff08\u4ee4\u548c&#8230;"},"content":{"rendered":"<p>\u753a\u5185\u4e2d\u5c0f\u4f01\u696d\u304c\u592a\u967d\u5149\u767a\u96fb\u8a2d\u5099\u3084\u96fb\u6c17\u81ea\u52d5\u8eca\u306e\u8a2d\u5099\u3092\u5c0e\u5165\u3059\u308b\u3053\u3068\u306b\u5bfe\u3057\u3066\u91d1\u878d\u6a5f\u95a2\u306e\u878d\u8cc7\u3092\u53d7\u3051\u305f\u5834\u5408\u306b\u3001\u305d\u306e\u5229\u5b50\u88dc\u7d66\u3092\u884c\u3044\u307e\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-153728","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/153728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=153728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}