{"id":153710,"date":"2026-03-21T14:19:02","date_gmt":"2026-03-21T14:19:02","guid":{"rendered":""},"modified":"2026-03-21T14:19:02","modified_gmt":"2026-03-21T14:19:02","slug":"%e9%b9%bf%e5%85%90%e5%b3%b6%e7%9c%8c%e9%b9%bf%e5%85%90%e5%b3%b6%e5%b8%82%ef%bc%9a%e3%80%8c%e5%b0%8f%e8%a6%8f%e6%a8%a1%e4%ba%8b%e6%a5%ad%e8%80%85ict%e5%b0%8e%e5%85%a5%e4%bf%83%e9%80%b2%e6%94%af","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e9%b9%bf%e5%85%90%e5%b3%b6%e7%9c%8c%e9%b9%bf%e5%85%90%e5%b3%b6%e5%b8%82%ef%bc%9a%e3%80%8c%e5%b0%8f%e8%a6%8f%e6%a8%a1%e4%ba%8b%e6%a5%ad%e8%80%85ict%e5%b0%8e%e5%85%a5%e4%bf%83%e9%80%b2%e6%94%af\/","title":{"rendered":"\u9e7f\u5150\u5cf6\u770c\u9e7f\u5150\u5cf6\u5e02\uff1a\u300c\u5c0f\u898f\u6a21\u4e8b\u696d\u8005ICT\u5c0e\u5165\u4fc3\u9032\u652f\u63f4\u4e8b\u696d\uff08\u30b9\u30c6\u30c3\u30d7&#8230;"},"content":{"rendered":"<p>\u5c0f\u898f\u6a21\u4e8b\u696d\u8005\u304c\u884c\u3046ICT\u3092\u6d3b\u7528\u3057\u305f\u696d\u52d9\u30d7\u30ed\u30bb\u30b9\u306e\u6539\u5584\u30fb\u52b9\u7387\u5316\u306b\u3088\u308b\u751f\u7523\u6027\u5411\u4e0a\u306e\u53d6\u7d44\u3092\u4fc3\u9032\u3059\u308b\u305f\u3081\u3001\u5c02\u9580\u5bb6\u306e\u30b5\u30dd\u30fc\u30c8\u3084ICT\u30c4\u30fc\u30eb\u5c0e\u5165\u306b\u3064\u3044\u3066\u652f\u63f4\u3057\u307e\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-153710","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/153710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=153710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}