{"id":152566,"date":"2026-03-21T14:18:35","date_gmt":"2026-03-21T14:18:35","guid":{"rendered":""},"modified":"2026-03-21T14:18:35","modified_gmt":"2026-03-21T14:18:35","slug":"%e3%80%8c%e3%83%87%e3%82%b8%e3%82%bf%e3%83%ab%e5%8c%96%e3%83%bbai%e5%b0%8e%e5%85%a5%e8%a3%9c%e5%8a%a9%e9%87%912026%ef%bc%88%e8%a4%87%e6%95%b0%e8%80%85%e9%80%a3%e6%90%ba%e3%83%87%e3%82%b8%e3%82%bf-2","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e3%80%8c%e3%83%87%e3%82%b8%e3%82%bf%e3%83%ab%e5%8c%96%e3%83%bbai%e5%b0%8e%e5%85%a5%e8%a3%9c%e5%8a%a9%e9%87%912026%ef%bc%88%e8%a4%87%e6%95%b0%e8%80%85%e9%80%a3%e6%90%ba%e3%83%87%e3%82%b8%e3%82%bf-2\/","title":{"rendered":"\u300c\u30c7\u30b8\u30bf\u30eb\u5316\u30fbAI\u5c0e\u5165\u88dc\u52a9\u91d12026\uff08\u8907\u6570\u8005\u9023\u643a\u30c7\u30b8\u30bf\u30eb\u5316\u30fbAI&#8230;"},"content":{"rendered":"<p>\u5546\u696d\u96c6\u7a4d\u5730\u3084\u30b5\u30d7\u30e9\u30a4\u30c1\u30a7\u30fc\u30f3\u306b\u95a2\u9023\u3059\u308b\u8907\u6570\u306e\u4e2d\u5c0f\u4f01\u696d\u30fb\u5c0f\u898f\u6a21\u4e8b\u696d\u8005\u7b49\u304c\u9023\u643a\u3057\u3001IT\u30c4\u30fc\u30eb\u3092\u5c0e\u5165\u3059\u308b\u3053\u3068\u306b\u3088\u308a\u751f\u7523\u6027\u5411\u4e0a\u3092\u56f3\u308b\u53d6\u7d44\u306b\u5bfe\u3057\u3066\u3001\u300c\u901a\u5e38\u67a0\u300d\u3088\u308a\u3082\u88dc\u52a9\u7387\u3092\u5f15\u304d\u4e0a\u3052\u3001\u8907\u6570\u8005\u3078\u306eIT\u30c4\u30fc\u30eb\u306e\u5c0e\u5165\u3092\u652f\u63f4\u3059\u308b\u3068\u3068\u3082\u306b\u3001\u52b9\u679c\u7684\u306b\u9023\u643a\u3059\u308b\u305f\u3081\u306e&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-152566","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/152566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=152566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}