{"id":152564,"date":"2026-03-21T14:18:35","date_gmt":"2026-03-21T14:18:35","guid":{"rendered":""},"modified":"2026-03-21T14:18:35","modified_gmt":"2026-03-21T14:18:35","slug":"%e3%80%8c%e3%83%87%e3%82%b8%e3%82%bf%e3%83%ab%e5%8c%96%e3%83%bbai%e5%b0%8e%e5%85%a5%e8%a3%9c%e5%8a%a9%e9%87%912026%ef%bc%88%e3%82%bb%e3%82%ad%e3%83%a5%e3%83%aa%e3%83%86%e3%82%a3%e5%af%be%e7%ad%96-4","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e3%80%8c%e3%83%87%e3%82%b8%e3%82%bf%e3%83%ab%e5%8c%96%e3%83%bbai%e5%b0%8e%e5%85%a5%e8%a3%9c%e5%8a%a9%e9%87%912026%ef%bc%88%e3%82%bb%e3%82%ad%e3%83%a5%e3%83%aa%e3%83%86%e3%82%a3%e5%af%be%e7%ad%96-4\/","title":{"rendered":"\u300c\u30c7\u30b8\u30bf\u30eb\u5316\u30fbAI\u5c0e\u5165\u88dc\u52a9\u91d12026\uff08\u30bb\u30ad\u30e5\u30ea\u30c6\u30a3\u5bfe\u7b56\u63a8\u9032\u67a0\uff09\u300d&#8230;"},"content":{"rendered":"<p>\u4e2d\u5c0f\u4f01\u696d\u30fb\u5c0f\u898f\u6a21\u4e8b\u696d\u8005\u7b49\u304cIT\u30c4\u30fc\u30eb\u3092\u5c0e\u5165\u3059\u308b\u305f\u3081\u306e\u7d4c\u8cbb\u306e\u4e00\u90e8\u3092\u88dc\u52a9\u3059\u308b\u3053\u3068\u306b\u3088\u308a\u3001\u4e2d\u5c0f\u4f01\u696d\u30fb\u5c0f\u898f\u6a21\u4e8b\u696d\u8005\u7b49\u306e\u30b5\u30a4\u30d0\u30fc\u30bb\u30ad\u30e5\u30ea\u30c6\u30a3\u5bfe\u7b56\u3092\u5f37\u5316\u3057\u3066\u3001\u30b5\u30a4\u30d0\u30fc\u30a4\u30f3\u30b7\u30c7\u30f3\u30c8\u3092\u539f\u56e0\u3068\u3057\u3066\u4e8b\u696d\u7d99\u7d9a\u304c\u56f0\u96e3\u3068\u306a\u308b\u7b49\u306e\u751f\u7523\u6027\u5411\u4e0a\u3092\u963b\u5bb3\u3059\u308b\u30ea\u30b9\u30af\u3092\u4f4e\u6e1b\u3059\u308b\u3068&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-152564","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/152564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=152564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}