{"id":152550,"date":"2026-03-21T14:18:35","date_gmt":"2026-03-21T14:18:35","guid":{"rendered":""},"modified":"2026-03-21T14:18:35","modified_gmt":"2026-03-21T14:18:35","slug":"%e3%80%8c%e3%83%87%e3%82%b8%e3%82%bf%e3%83%ab%e5%8c%96%e3%83%bbai%e5%b0%8e%e5%85%a5%e8%a3%9c%e5%8a%a9%e9%87%912026%ef%bc%88%e9%80%9a%e5%b8%b8%e6%9e%a0%ef%bc%89%e3%80%8d%e2%89%aa2%e6%ac%a1%e7%b7%a0","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e3%80%8c%e3%83%87%e3%82%b8%e3%82%bf%e3%83%ab%e5%8c%96%e3%83%bbai%e5%b0%8e%e5%85%a5%e8%a3%9c%e5%8a%a9%e9%87%912026%ef%bc%88%e9%80%9a%e5%b8%b8%e6%9e%a0%ef%bc%89%e3%80%8d%e2%89%aa2%e6%ac%a1%e7%b7%a0\/","title":{"rendered":"\u300c\u30c7\u30b8\u30bf\u30eb\u5316\u30fbAI\u5c0e\u5165\u88dc\u52a9\u91d12026\uff08\u901a\u5e38\u67a0\uff09\u300d\u226a2\u6b21\u7de0\u5207\u226b"},"content":{"rendered":"<p>\u4e2d\u5c0f\u4f01\u696d\u30fb\u5c0f\u898f\u6a21\u4e8b\u696d\u8005\u7b49\u306e\u52b4\u50cd\u751f\u7523\u6027\u306e\u5411\u4e0a\u3092\u76ee\u7684\u3068\u3057\u3066\u3001\u696d\u52d9\u52b9\u7387\u5316\u3084DX\u7b49\u306b\u5411\u3051\u305f IT\u30c4\u30fc\u30eb\u306e\u5c0e\u5165\u3092\u652f\u63f4\u3059\u308b\u88dc\u52a9\u91d1\u3067\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-152550","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/152550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=152550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}