{"id":151074,"date":"2026-03-21T14:18:04","date_gmt":"2026-03-21T14:18:04","guid":{"rendered":""},"modified":"2026-03-21T14:18:04","modified_gmt":"2026-03-21T14:18:04","slug":"%e3%80%8c%e3%82%aa%e3%83%95%e3%82%a3%e3%82%b9%e7%a7%bb%e8%bb%a2%e3%83%bb%e6%96%b0%e8%a8%ad%e3%81%ab%e9%96%a2%e3%81%99%e3%82%8b%e8%a3%9c%e5%8a%a9%e5%88%b6%e5%ba%a6%e3%80%8d%ef%bc%88%e4%bb%a4%e5%92%8c7","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e3%80%8c%e3%82%aa%e3%83%95%e3%82%a3%e3%82%b9%e7%a7%bb%e8%bb%a2%e3%83%bb%e6%96%b0%e8%a8%ad%e3%81%ab%e9%96%a2%e3%81%99%e3%82%8b%e8%a3%9c%e5%8a%a9%e5%88%b6%e5%ba%a6%e3%80%8d%ef%bc%88%e4%bb%a4%e5%92%8c7\/","title":{"rendered":"\u300c\u30aa\u30d5\u30a3\u30b9\u79fb\u8ee2\u30fb\u65b0\u8a2d\u306b\u95a2\u3059\u308b\u88dc\u52a9\u5236\u5ea6\u300d\uff08\u4ee4\u548c7\u5e74\u5ea6\uff09"},"content":{"rendered":"<p>\u30b3\u30ed\u30ca\u798d\u3092\u7d4c\u3066\u30aa\u30d5\u30a3\u30b9\u306e\u5730\u65b9\u5206\u6563\u304c\u9032\u3080\u306a\u304b\u3001\u4e8b\u52d9\u7cfb\u4f01\u696d\u7b49\u306e\u65b0\u305f\u306a\u7523\u696d\u96c6\u7a4d\u3092\u671f\u3059\u308b\u305f\u3081\u3001\u6b21\u4e16\u4ee3\u81ea\u52d5\u8eca\u30fb\u5b87\u5b99\u30fbGX\u30fbDX\u7b49\u3001\u4eca\u5f8c\u6210\u9577\u304c\u671f\u5f85\u3055\u308c\u308b\u5206\u91ce\u306b\u3064\u3044\u3066\u652f\u63f4\u3059\u308b\u65b0\u305f\u306a\u30e1\u30cb\u30e5\u30fc\u3092\u65e2\u5b58\u88dc\u52a9\u5236\u5ea6\u306b\u52a0\u3048\u3001\u4e8b\u52d9\u7cfb\u4f01\u696d\u306e\u8a98\u81f4\u4fc3\u9032\u3092\u56f3\u308a\u307e\u3059\u3002\u203b\u672c\u88dc\u52a9&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-151074","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/151074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=151074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}