{"id":149305,"date":"2026-03-21T14:17:28","date_gmt":"2026-03-21T14:17:28","guid":{"rendered":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e3%80%8c%e3%82%bc%e3%83%ad%e3%82%a8%e3%83%9f%e3%83%83%e3%82%b7%e3%83%a7%e3%83%b3%e8%88%b9%e7%ad%89%e3%81%ae%e5%bb%ba%e9%80%a0%e4%bf%83%e9%80%b2%e4%ba%8b%e6%a5%ad%e3%80%8d\/"},"modified":"2026-03-21T14:17:28","modified_gmt":"2026-03-21T14:17:28","slug":"%e3%80%8c%e3%82%bc%e3%83%ad%e3%82%a8%e3%83%9f%e3%83%83%e3%82%b7%e3%83%a7%e3%83%b3%e8%88%b9%e7%ad%89%e3%81%ae%e5%bb%ba%e9%80%a0%e4%bf%83%e9%80%b2%e4%ba%8b%e6%a5%ad%e3%80%8d","status":"publish","type":"subsidy","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/subsidy\/%e3%80%8c%e3%82%bc%e3%83%ad%e3%82%a8%e3%83%9f%e3%83%83%e3%82%b7%e3%83%a7%e3%83%b3%e8%88%b9%e7%ad%89%e3%81%ae%e5%bb%ba%e9%80%a0%e4%bf%83%e9%80%b2%e4%ba%8b%e6%a5%ad%e3%80%8d\/","title":{"rendered":"\u300c\u30bc\u30ed\u30a8\u30df\u30c3\u30b7\u30e7\u30f3\u8239\u7b49\u306e\u5efa\u9020\u4fc3\u9032\u4e8b\u696d\u300d"},"content":{"rendered":"<p>\u30bc\u30ed\u30a8\u30df\u30c3\u30b7\u30e7\u30f3\u8239\u7b49\u306e\u56fd\u5185\u751f\u7523\u4f53\u5236\u3092\u4e16\u754c\u306b\u5148\u99c6\u3051\u3066\u69cb\u7bc9\u3057\u3001\u5e02\u5834\u5c0e\u5165\u4fc3\u9032\u306b\u3088\u308bCO2\u306e\u6392\u51fa\u524a\u6e1b\u3092\u9032\u3081\u308b\u3068\u3068\u3082\u306b\u7523\u696d\u7af6\u4e89\u529b\u5f37\u5316\u30fb\u7d4c\u6e08\u6210\u9577\u3092\u56f3\u308b\u3053\u3068\u3092\u76ee\u7684\u3068\u3057\u307e\u3059\u3002<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-149305","subsidy","type-subsidy","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy\/149305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/subsidy"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/subsidy"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=149305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}