{"id":206494,"date":"2026-06-09T05:40:14","date_gmt":"2026-06-09T05:40:14","guid":{"rendered":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/?p=206494"},"modified":"2026-06-09T05:40:14","modified_gmt":"2026-06-09T05:40:14","slug":"iwate-clinic-multilingual-support-subsidy-09396","status":"publish","type":"post","link":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/iwate-clinic-multilingual-support-subsidy-09396\/","title":{"rendered":"\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af\u304c\u591a\u8a00\u8a9e\u5bfe\u5fdc\u306b\u4f7f\u3048\u308b\u88dc\u52a9\u91d1\u306f\uff1f\u7533\u8acb\u524d\u306e\u78ba\u8a8d\u30dd\u30a4\u30f3\u30c8"},"content":{"rendered":"<p>\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af\u304c<strong class=\"article-key-emphasis\"><u>\u591a\u8a00\u8a9e\u5bfe\u5fdc\u306b\u4f7f\u3048\u308b\u88dc\u52a9\u91d1<\/u><\/strong>\u306f\uff1f\u7533\u8acb\u524d\u306e\u78ba\u8a8d\u30dd\u30a4\u30f3\u30c8\u3092\u8abf\u3079\u308b\u4eba\u306f\u3001\u300c\u81ea\u793e\u3067\u3082\u4f7f\u3048\u308b\u306e\u304b\u306a\u300d\u3068\u77e5\u308a\u305f\u3044\u306f\u305a\u3067\u3059\u3002\u88dc\u52a9\u91d1\u306f\u3001\u540d\u524d\u3060\u3051\u3067\u306f\u6c7a\u307e\u308a\u307e\u305b\u3093\u3002\u5ca9\u624b\u770c\u3001\u30af\u30ea\u30cb\u30c3\u30af\u3001\u591a\u8a00\u8a9e\u5bfe\u5fdc\u306a\u3069\u306e\u6761\u4ef6\u3067\u3001\u4f7f\u3048\u308b\u3082\u306e\u304c\u5909\u308f\u308a\u307e\u3059\u3002<\/p>\n<p><strong class=\"article-key-emphasis\"><u>\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af<\/u><\/strong>\u306b\u5927\u5207\u306a\u306e\u306f\u3001\u3080\u305a\u304b\u3057\u3044\u7533\u8acb\u66f8\u3092\u3044\u304d\u306a\u308a\u66f8\u304f\u3053\u3068\u3067\u306f\u3042\u308a\u307e\u305b\u3093\u3002\u307e\u305a\u3001\u4f7f\u3048\u306a\u3044\u5236\u5ea6\u3092\u65e9\u3081\u306b\u5916\u3059\u3053\u3068\u3067\u3059\u3002\u3053\u306e\u8a18\u4e8b\u3067\u306f\u3001\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af\u3092\u5165\u53e3\u306b\u3057\u3066\u3001\u5019\u88dc\u306e\u63a2\u3057\u65b9\u3068\u78ba\u8a8d\u3059\u308b\u9806\u756a\u3092\u8aac\u660e\u3057\u307e\u3059\u3002<\/p>\n<div class=\"article-summary-panel\">\n<p class=\"summary-label\">\u3053\u306e\u8a18\u4e8b\u306e\u7d50\u8ad6<\/p>\n<ul class=\"article-key-points\">\n<li><strong class=\"article-key-emphasis\"><u>\u5ca9\u624b\u770c \u30af\u30ea\u30cb\u30c3\u30af \u591a\u8a00\u8a9e\u5bfe\u5fdc \u88dc\u52a9\u91d1\u306f\u3001\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af\u304c\u591a\u8a00\u8a9e\u5bfe\u5fdc\u306b\u4f7f\u3048\u308b\u88dc\u52a9\u91d1\u3092\u78ba\u8a8d\u3059\u308b\u305f\u3081\u306e\u691c\u7d22\u30c6\u30fc\u30de\u3067\u3059\u3002<\/u><\/strong><\/li>\n<li><strong class=\"article-key-emphasis\"><u>\u6700\u521d\u306b\u898b\u308b\u3079\u304d\u9806\u756a\u306f\u300c\u5bfe\u8c61\u8005\u300d\u300c\u5bfe\u8c61\u7d4c\u8cbb\u300d\u300c\u7533\u8acb\u6642\u671f\u300d\u300c\u63a1\u629e\u5f8c\u306e\u5831\u544a\u300d\u3067\u3059\u3002<\/u><\/strong><\/li>\n<li><strong class=\"article-key-emphasis\"><u>\u8ff7\u3046\u5834\u5408\u306f\u6761\u4ef6\u3092\u5165\u529b\u3057\u3066\u5019\u88dc\u5236\u5ea6\u3092\u8a3a\u65ad\u3057\u3001\u7de0\u5207\u3068\u5bfe\u8c61\u7d4c\u8cbb\u304b\u3089\u512a\u5148\u9806\u4f4d\u3092\u4ed8\u3051\u307e\u3059\u3002<\/u><\/strong><\/li>\n<\/ul>\n<\/div>\n<div class=\"article-fact-grid\">\n<div><span>\u4eca\u56de\u306e\u30c6\u30fc\u30de<\/span><strong>\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af<\/strong><\/div>\n<div><span>\u78ba\u8a8d\u3059\u308b\u652f\u63f4<\/span><strong>\u88dc\u52a9\u91d1<\/strong><\/div>\n<div><span>\u5bfe\u8c61\u9818\u57df<\/span><strong>\u5ca9\u624b\u770c<\/strong><\/div>\n<div><span>\u4e3b\u306a\u8aad\u8005<\/span><strong>\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af<\/strong><\/div>\n<div><span>\u691c\u8a0e\u6bb5\u968e<\/span><strong>\u5019\u88dc\u6bd4\u8f03\u306e\u9014\u4e2d<\/strong><\/div>\n<div><span>\u8aad\u307f\u65b9<\/span><strong>\u5730\u57df\u696d\u7a2e\u7528\u9014\u30b3\u30e9\u30e0<\/strong><\/div>\n<\/div>\n<h2>\u5236\u5ea6\u540d\u3088\u308a\u5148\u306b\u6574\u7406\u3057\u305f\u3044\u524d\u63d0<\/h2>\n<p>\u307e\u305a\u898b\u308b\u306e\u306f\u3001\u91d1\u984d\u306e\u5927\u304d\u3055\u3067\u306f\u3042\u308a\u307e\u305b\u3093\u3002\u3060\u308c\u304c\u4f7f\u3048\u308b\u304b\u3001\u4f55\u306b\u4f7f\u3048\u308b\u304b\u3001\u3044\u3064\u59cb\u3081\u3066\u3088\u3044\u304b\u3092\u898b\u307e\u3059\u3002\u3053\u3053\u3092\u98db\u3070\u3059\u3068\u3001\u3042\u3068\u3067\u3084\u308a\u76f4\u3057\u306b\u306a\u308a\u3084\u3059\u3044\u3067\u3059\u3002<\/p>\n<p>\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af\u304c<strong class=\"article-key-emphasis\"><u>\u591a\u8a00\u8a9e\u5bfe\u5fdc\u306b\u4f7f\u3048\u308b\u88dc\u52a9\u91d1<\/u><\/strong>\u3092\u8003\u3048\u308b\u3068\u304d\u306f\u3001\u5148\u306b\u30e1\u30e2\u3092\u4f5c\u308a\u307e\u3057\u3087\u3046\u3002\u300c\u4f55\u306b\u4f7f\u3046\u304a\u91d1\u304b\u300d\u300c\u3044\u3064\u59cb\u3081\u308b\u304b\u300d\u300c\u7d42\u308f\u3063\u305f\u3042\u3068\u4f55\u304c\u826f\u304f\u306a\u308b\u304b\u300d\u3092\u5206\u3051\u3066\u66f8\u304d\u307e\u3059\u3002\u5019\u88dc\u6bd4\u8f03\u306e\u9014\u4e2d\u306e\u6bb5\u968e\u3067\u306f\u3001\u5019\u88dc\u3092\u5c11\u306a\u304f\u3059\u308b\u3053\u3068\u304c\u5148\u3067\u3059\u3002<\/p>\n<h2>\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af\u3067\u307e\u305a\u5207\u308a\u5206\u3051\u308b\u6761\u4ef6<\/h2>\n<p><strong class=\"article-key-emphasis\"><u>\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af<\/u><\/strong>\u3067\u898b\u308b\u6761\u4ef6\u306f\u3001\u5927\u304d\u304f\u5206\u3051\u3066\u4e09\u3064\u3067\u3059\u3002\u4f1a\u793e\u306e\u60c5\u5831\u3001\u4e8b\u696d\u306e\u4e2d\u8eab\u3001\u4f7f\u3046\u304a\u91d1\u3068\u6642\u671f\u3067\u3059\u3002\u3053\u3053\u3092\u5148\u306b\u898b\u308b\u3068\u3001\u5408\u308f\u306a\u3044\u5236\u5ea6\u3092\u65e9\u304f\u5916\u305b\u307e\u3059\u3002<\/p>\n<div class=\"article-context-cards\">\n<section>\n<h3><strong class=\"article-key-emphasis\"><u>\u5730\u57df\u6761\u4ef6<\/u><\/strong><\/h3>\n<p>\u5ca9\u624b\u770c\u3067\u306f\u3001\u56fd\u306e\u5236\u5ea6\u306b\u52a0\u3048\u3066\u90fd\u9053\u5e9c\u770c\u30fb\u5e02\u533a\u753a\u6751\u306e\u4e0a\u4e57\u305b\u652f\u63f4\u3084\u72ec\u81ea\u67a0\u3092\u78ba\u8a8d\u3057\u307e\u3059\u3002<\/p>\n<\/section>\n<section>\n<h3><strong class=\"article-key-emphasis\"><u>\u696d\u7a2e\u306e\u8ad6\u70b9<\/u><\/strong><\/h3>\n<p>\u533b\u7642\u30fb\u798f\u7949\u30fb\u4fdd\u80b2\u7cfb\u3067\u306f\u3001\u8a18\u9332\u696d\u52d9\u306e\u52b9\u7387\u5316\u3001\u4e88\u7d04\u30fb\u53d7\u4ed8\u3001\u8077\u54e1\u5b9a\u7740\u3001\u30b5\u30fc\u30d3\u30b9\u54c1\u8cea\u304c\u8ad6\u70b9\u306b\u306a\u308a\u3084\u3059\u3044\u3067\u3059\u3002<\/p>\n<\/section>\n<section>\n<h3><strong class=\"article-key-emphasis\"><u>\u4f7f\u3044\u9053\u306e\u8ad6\u70b9<\/u><\/strong><\/h3>\n<p>\u591a\u8a00\u8a9e\u5bfe\u5fdc\u3067\u65b0\u898f\u9867\u5ba2\u306e\u7372\u5f97\u3001\u5ba2\u5358\u4fa1\u5411\u4e0a\u3001\u5546\u8ac7\u6570\u5897\u52a0\u3092\u72d9\u3046\u5834\u5408\u306b\u5411\u3044\u3066\u3044\u307e\u3059\u3002<\/p>\n<\/section>\n<\/div>\n<h2>\u5019\u88dc\u3092\u7d5e\u308b\u524d\u306b\u898b\u3066\u304a\u304d\u305f\u3044\u3053\u3068<\/h2>\n<p>\u88dc\u52a9\u91d1\u3092\u9078\u3076\u524d\u306b\u3001\u304b\u3093\u305f\u3093\u306a\u30e1\u30e2\u3092\u4f5c\u308b\u3068\u8ff7\u3044\u306b\u304f\u304f\u306a\u308a\u307e\u3059\u3002\u591a\u8a00\u8a9e\u5bfe\u5fdc\u306b\u4f7f\u3046\u304a\u91d1\u3092\u3001\u4f7f\u3048\u305d\u3046\u306a\u8cbb\u7528\u3068\u4f7f\u3048\u306a\u3055\u305d\u3046\u306a\u8cbb\u7528\u306b\u5206\u3051\u307e\u3059\u3002\u81ea\u793e\u3067\u51fa\u305b\u308b\u304a\u91d1\u3082\u66f8\u3044\u3066\u304a\u304d\u307e\u3059\u3002<\/p>\n<p>\u540c\u3058\u88dc\u52a9\u91d1\u3067\u3082\u3001\u4f7f\u3048\u308b\u8cbb\u7528\u306f\u5236\u5ea6\u3054\u3068\u306b\u3061\u304c\u3044\u307e\u3059\u3002<strong class=\"article-key-emphasis\"><u>\u898b\u7a4d\u66f8<\/u><\/strong>\u3001\u59cb\u3081\u308b\u65e5\u3001\u652f\u6255\u3046\u65e5\u3082\u898b\u307e\u3059\u3002\u5c11\u3057\u624b\u9593\u3067\u3082\u3001\u5148\u306b\u5206\u3051\u3066\u304a\u304f\u3068\u3001\u3042\u3068\u3067\u8a08\u753b\u3092\u4f5c\u308a\u76f4\u3059\u3053\u3068\u3092\u6e1b\u3089\u305b\u307e\u3059\u3002<\/p>\n<h2>\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af\u3067\u5019\u88dc\u306b\u306a\u308a\u3084\u3059\u3044\u5236\u5ea6<\/h2>\n<p>\u5ca9\u624b\u770c \u30af\u30ea\u30cb\u30c3\u30af \u591a\u8a00\u8a9e\u5bfe\u5fdc \u88dc\u52a9\u91d1\u3067\u898b\u308b\u5236\u5ea6\u306f\u3001\u5730\u57df\u3084\u696d\u7a2e\u3067\u5909\u308f\u308a\u307e\u3059\u3002\u4f7f\u3044\u9053\u3067\u3082\u5909\u308f\u308a\u307e\u3059\u3002\u6700\u521d\u304b\u3089\u4e00\u3064\u306b\u6c7a\u3081\u305a\u3001\u3044\u304f\u3064\u304b\u306b\u5206\u3051\u3066\u6bd4\u3079\u307e\u3057\u3087\u3046\u3002<\/p>\n<table class=\"article-compare-table\">\n<thead>\n<tr>\n<th>\u5019\u88dc<\/th>\n<th>\u5411\u3044\u3066\u3044\u308b\u30b1\u30fc\u30b9<\/th>\n<th>\u78ba\u8a8d\u3059\u308b\u3082\u306e<\/th>\n<th>\u6ce8\u610f\u70b9<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th><strong class=\"article-key-emphasis\"><u>\u30c7\u30b8\u30bf\u30eb\u5316\u30fbAI\u5c0e\u5165\u7cfb<\/u><\/strong><\/th>\n<td>\u591a\u8a00\u8a9e\u5bfe\u5fdc\u304cIT\u3001AI\u3001\u696d\u52d9\u7ba1\u7406\u3001\u4e88\u7d04\u3001\u4f1a\u8a08\u306a\u3069\u306b\u95a2\u308f\u308b\u5834\u5408\u306b\u78ba\u8a8d\u3057\u307e\u3059\u3002<\/td>\n<td>\u6240\u5728\u5730\u3001\u696d\u7a2e\u3001\u5f93\u696d\u54e1\u6570\u3001\u8cc7\u672c\u91d1\u3001\u6295\u8cc7\u76ee\u7684\u3001\u5c0e\u5165\u4e88\u5b9a\u6642\u671f\u3092\u78ba\u8a8d\u3057\u307e\u3059\u3002<\/td>\n<td>\u8a3a\u65ad\u3084\u4e00\u89a7\u306f\u5019\u88dc\u306e\u7d5e\u308a\u8fbc\u307f\u3067\u3042\u308a\u3001\u7533\u8acb\u53ef\u5426\u306e\u6700\u7d42\u5224\u65ad\u3067\u306f\u3042\u308a\u307e\u305b\u3093\u3002<\/td>\n<\/tr>\n<tr>\n<th><strong class=\"article-key-emphasis\"><u>\u8ca9\u8def\u958b\u62d3\u30fb\u96c6\u5ba2\u7cfb<\/u><\/strong><\/th>\n<td>\u591a\u8a00\u8a9e\u5bfe\u5fdc\u304c\u58f2\u4e0a\u62e1\u5927\u3001Web\u5236\u4f5c\u3001\u5e83\u544a\u3001\u5c55\u793a\u4f1a\u306b\u95a2\u308f\u308b\u5834\u5408\u306b\u5019\u88dc\u306b\u306a\u308a\u307e\u3059\u3002<\/td>\n<td>\u5bfe\u8c61\u7d4c\u8cbb\u3001\u88dc\u52a9\u7387\u3001\u4e0a\u9650\u984d\u3001\u767a\u6ce8\u6642\u671f\u3001\u5fc5\u8981\u66f8\u985e\u3092\u516c\u52df\u8981\u9818\u3067\u78ba\u8a8d\u3057\u307e\u3059\u3002<\/td>\n<td>\u5e74\u5ea6\u3084\u516c\u52df\u56de\u3067\u8981\u4ef6\u304c\u5909\u308f\u308b\u305f\u3081\u3001\u904e\u53bb\u60c5\u5831\u3060\u3051\u3067\u9032\u3081\u306a\u3044\u3088\u3046\u306b\u3057\u307e\u3059\u3002<\/td>\n<\/tr>\n<tr>\n<th><strong class=\"article-key-emphasis\"><u>\u7701\u529b\u5316\u30fb\u8a2d\u5099\u6295\u8cc7\u7cfb<\/u><\/strong><\/th>\n<td>\u591a\u8a00\u8a9e\u5bfe\u5fdc\u304c\u8a2d\u5099\u5c0e\u5165\u3001\u696d\u52d9\u52b9\u7387\u5316\u3001\u7701\u4eba\u5316\u306b\u3064\u306a\u304c\u308b\u5834\u5408\u306b\u78ba\u8a8d\u3057\u307e\u3059\u3002<\/td>\n<td>\u898b\u7a4d\u66f8\u3001\u4e8b\u696d\u8a08\u753b\u3001\u8cc7\u91d1\u8a08\u753b\u3001\u76f8\u8ac7\u6642\u306b\u4f1d\u3048\u308b\u524d\u63d0\u6761\u4ef6\u3092\u6574\u7406\u3057\u307e\u3059\u3002<\/td>\n<td>\u76f8\u8ac7\u524d\u306b\u6761\u4ef6\u304c\u66d6\u6627\u3060\u3068\u3001\u5bfe\u8c61\u5916\u306e\u5236\u5ea6\u306b\u6642\u9593\u3092\u4f7f\u3044\u3084\u3059\u304f\u306a\u308a\u307e\u3059\u3002<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>\u8907\u6570\u5019\u88dc\u3092\u6bd4\u3079\u308b\u3068\u304d\u306e\u8003\u3048\u65b9<\/h2>\n<p>\u5019\u88dc\u304c\u3044\u304f\u3064\u3082\u51fa\u305f\u3089\u3001\u4e0a\u9650\u984d\u3060\u3051\u3067\u9078\u3070\u306a\u3044\u3067\u304f\u3060\u3055\u3044\u3002\u5bfe\u8c61\u306b\u306a\u308b\u8cbb\u7528\u3001\u3057\u3081\u5207\u308a\u3001\u5148\u306b\u51fa\u3059\u304a\u91d1\u3001\u3042\u3068\u3067\u51fa\u3059\u5831\u544a\u3092\u6bd4\u3079\u307e\u3059\u3002\u81ea\u793e\u3067\u672c\u5f53\u306b\u9032\u3081\u3089\u308c\u308b\u3082\u306e\u3092\u9078\u3076\u3053\u3068\u304c\u5927\u5207\u3067\u3059\u3002<\/p>\n<p>\u30af\u30ea\u30cb\u30c3\u30af\u306e\u5834\u5408\u3082\u3001\u696d\u7a2e\u540d\u3060\u3051\u3067\u306f\u6c7a\u307e\u308a\u307e\u305b\u3093\u3002\u58f2\u4e0a\u3001\u4f5c\u696d\u6642\u9593\u3001\u6765\u5e97\u6570\u3001\u6b8b\u696d\u6642\u9593\u306a\u3069\u3001\u3088\u304f\u3057\u305f\u3044\u6570\u5b57\u3092\u4e00\u3064\u6c7a\u3081\u307e\u3059\u3002\u305d\u306e\u6570\u5b57\u304c\u3042\u308b\u3068\u3001\u4f55\u306e\u305f\u3081\u306e\u53d6\u308a\u7d44\u307f\u304b\u3092\u8aac\u660e\u3057\u3084\u3059\u304f\u306a\u308a\u307e\u3059\u3002<\/p>\n<h2>\u7533\u8acb\u524d\u306b\u78ba\u8a8d\u3059\u308b4\u3064\u306e\u624b\u9806<\/h2>\n<p>\u7533\u8acb\u306e\u524d\u306b\u306f\u3001\u9806\u756a\u304c\u5927\u4e8b\u3067\u3059\u3002\u5148\u306b\u6761\u4ef6\u3092\u6574\u7406\u3057\u307e\u3059\u3002\u6b21\u306b\u8cbb\u7528\u3068\u65e5\u7a0b\u3092\u898b\u307e\u3059\u3002\u6700\u5f8c\u306b\u3001\u66f8\u985e\u3068\u6570\u5b57\u3092\u305d\u308d\u3048\u307e\u3059\u3002<\/p>\n<ol class=\"article-steps\">\n<li><span>1<\/span>\n<div><strong class=\"article-key-emphasis\"><u>\u6761\u4ef6\u3092\u6574\u7406\u3059\u308b<\/u><\/strong><\/p>\n<p>\u6240\u5728\u5730\u3001\u696d\u7a2e\u3001\u5f93\u696d\u54e1\u6570\u3001\u8cc7\u672c\u91d1\u3001\u6295\u8cc7\u5185\u5bb9\u3001\u5c0e\u5165\u6642\u671f\u3092\u5148\u306b\u66f8\u304d\u51fa\u3057\u307e\u3059\u3002<\/p>\n<\/div>\n<\/li>\n<li><span>2<\/span>\n<div><strong class=\"article-key-emphasis\"><u>\u5bfe\u8c61\u7d4c\u8cbb\u3092\u78ba\u8a8d\u3059\u308b<\/u><\/strong><\/p>\n<p>\u591a\u8a00\u8a9e\u5bfe\u5fdc\u306b\u95a2\u3059\u308b\u898b\u7a4d\u66f8\u3084\u4ed5\u69d8\u66f8\u3092\u7528\u610f\u3057\u3001\u5bfe\u8c61\u5916\u8cbb\u7528\u304c\u6df7\u3056\u3063\u3066\u3044\u306a\u3044\u304b\u78ba\u8a8d\u3057\u307e\u3059\u3002<\/p>\n<\/div>\n<\/li>\n<li><span>3<\/span>\n<div><strong class=\"article-key-emphasis\"><u>\u7de0\u5207\u304b\u3089\u9006\u7b97\u3059\u308b<\/u><\/strong><\/p>\n<p>G\u30d3\u30baID\u3001\u4e8b\u696d\u8a08\u753b\u3001\u898b\u7a4d\u3001\u7533\u8acb\u7de0\u5207\u3001\u4ea4\u4ed8\u6c7a\u5b9a\u5f8c\u306e\u767a\u6ce8\u6642\u671f\u3092\u78ba\u8a8d\u3057\u307e\u3059\u3002<\/p>\n<\/div>\n<\/li>\n<li><span>4<\/span>\n<div><strong class=\"article-key-emphasis\"><u>\u63a1\u629e\u5f8c\u3092\u7ba1\u7406\u3059\u308b<\/u><\/strong><\/p>\n<p>\u5b9f\u7e3e\u5831\u544a\u3001\u652f\u6255\u3044\u8a3c\u6191\u3001\u6210\u679c\u5831\u544a\u307e\u3067\u7ba1\u7406\u3067\u304d\u308b\u4f53\u5236\u3092\u4f5c\u308a\u307e\u3059\u3002<\/p>\n<\/div>\n<\/li>\n<\/ol>\n<h2>\u63a1\u629e\u3055\u308c\u3084\u3059\u3044\u8a08\u753b\u306b\u8fd1\u3065\u3051\u308b\u8003\u3048\u65b9<\/h2>\n<p>\u88dc\u52a9\u91d1\u3067\u306f\u3001\u300c\u4f55\u3092\u8cb7\u3046\u304b\u300d\u3060\u3051\u3067\u306f\u8db3\u308a\u307e\u305b\u3093\u3002\u300c\u306a\u305c\u5fc5\u8981\u304b\u300d\u3082\u5927\u5207\u3067\u3059\u3002\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af\u304c<strong class=\"article-key-emphasis\"><u>\u591a\u8a00\u8a9e\u5bfe\u5fdc\u306b\u4f7f\u3048\u308b\u88dc\u52a9\u91d1<\/u><\/strong>\u3092\u8003\u3048\u308b\u5834\u5408\u3082\u3001\u58f2\u4e0a\u3084\u4f5c\u696d\u6642\u9593\u306a\u3069\u3001\u5909\u308f\u308b\u6570\u5b57\u3092\u4e00\u3064\u6c7a\u3081\u3066\u304a\u304d\u307e\u3057\u3087\u3046\u3002<\/p>\n<blockquote class=\"article-note\"><p>\u4ea4\u4ed8\u6c7a\u5b9a\u524d\u306e\u767a\u6ce8\u30fb\u5951\u7d04\u30fb\u652f\u6255\u3044\u306f\u5bfe\u8c61\u5916\u306b\u306a\u308b\u3053\u3068\u304c\u3042\u308a\u307e\u3059\u3002\u898b\u7a4d\u3092\u53d6\u308b\u6bb5\u968e\u304b\u3089\u3001\u767a\u6ce8\u30bf\u30a4\u30df\u30f3\u30b0\u3068\u8a3c\u6191\u7ba1\u7406\u3092\u610f\u8b58\u3057\u3066\u304f\u3060\u3055\u3044\u3002<\/p><\/blockquote>\n<h2>\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af\u3067\u907f\u3051\u305f\u3044\u6ce8\u610f\u70b9<\/h2>\n<p>\u5931\u6557\u3057\u3084\u3059\u3044\u70b9\u306f\u3001\u5148\u306b\u77e5\u3063\u3066\u304a\u304f\u3068\u9632\u304e\u3084\u3059\u3044\u3067\u3059\u3002\u3068\u304f\u306b\u3001\u59cb\u3081\u308b\u65e5\u3001\u652f\u6255\u3046\u65e5\u3001\u540c\u3058\u8cbb\u7528\u306e\u91cd\u8907\u306b\u306f\u6c17\u3092\u3064\u3051\u307e\u3057\u3087\u3046\u3002<\/p>\n<ul class=\"article-warning-list\">\n<li><strong class=\"article-key-emphasis\"><u>\u691c\u7d22\u7d50\u679c\u306e\u5236\u5ea6\u540d\u3060\u3051\u3067\u6c7a\u3081\u308b<\/u><\/strong>\n<p>\u5236\u5ea6\u540d\u3084\u4e0a\u9650\u984d\u3060\u3051\u3067\u5224\u65ad\u305b\u305a\u3001\u767a\u6ce8\u6642\u671f\u3068\u8a3c\u6191\u7ba1\u7406\u307e\u3067\u78ba\u8a8d\u3057\u307e\u3059\u3002<\/p>\n<\/li>\n<li><strong class=\"article-key-emphasis\"><u>\u591a\u8a00\u8a9e\u5bfe\u5fdc\u306e\u5bfe\u8c61\u7d4c\u8cbb\u3092\u5e83\u304f\u898b\u3059\u304e\u308b<\/u><\/strong>\n<p>\u5358\u306a\u308b\u30b5\u30a4\u30c8\u66f4\u65b0\u3084\u5e83\u544a\u51fa\u7a3f\u3067\u7d42\u308f\u308a\u3001\u8ca9\u8def\u958b\u62d3\u306e\u8a08\u753b\u3068\u3057\u3066\u5f31\u304f\u898b\u3048\u308b\u3053\u3068\u3067\u3059\u3002\u898b\u7a4d\u66f8\u3067\u306f\u5bfe\u8c61\u7d4c\u8cbb\u3068\u5bfe\u8c61\u5916\u7d4c\u8cbb\u3092\u5206\u3051\u3066\u304a\u304d\u307e\u3057\u3087\u3046\u3002<\/p>\n<\/li>\n<li><strong class=\"article-key-emphasis\"><u>\u30af\u30ea\u30cb\u30c3\u30af\u306a\u3089\u5fc5\u305a\u4f7f\u3048\u308b\u3068\u601d\u3044\u8fbc\u3080<\/u><\/strong>\n<p>\u30af\u30ea\u30cb\u30c3\u30af\u3068\u3044\u3046\u696d\u7a2e\u540d\u3060\u3051\u3067\u5bfe\u8c61\u53ef\u5426\u3092\u5224\u65ad\u3059\u308b\u3053\u3068\u3067\u3059\u3002\u540c\u3058\u696d\u7a2e\u3067\u3082\u3001\u5f93\u696d\u54e1\u6570\u3001\u8cc7\u672c\u91d1\u3001\u5c0e\u5165\u76ee\u7684\u3001\u5b9f\u65bd\u5834\u6240\u3067\u7d50\u679c\u304c\u5909\u308f\u308a\u307e\u3059\u3002<\/p>\n<\/li>\n<li><strong class=\"article-key-emphasis\"><u>\u5ca9\u624b\u770c\u306e\u5236\u5ea6\u3092\u90fd\u9053\u5e9c\u770c\u3060\u3051\u3067\u63a2\u3059<\/u><\/strong>\n<p>\u5e02\u533a\u753a\u6751\u3001\u5546\u5de5\u4f1a\u8b70\u6240\u3001\u7523\u696d\u632f\u8208\u6a5f\u95a2\u306b\u3082\u5c0f\u898f\u6a21\u306a\u52df\u96c6\u304c\u51fa\u308b\u3053\u3068\u304c\u3042\u308a\u307e\u3059\u3002\u56fd\u5236\u5ea6\u3068\u306e\u4f75\u7528\u53ef\u5426\u3082\u78ba\u8a8d\u3057\u3066\u304f\u3060\u3055\u3044\u3002<\/p>\n<\/li>\n<\/ul>\n<h2>\u3088\u304f\u3042\u308b\u8cea\u554f<\/h2>\n<div class=\"article-faq\">\n<details>\n<summary>\u591a\u8a00\u8a9e\u5bfe\u5fdc\u306f\u5fc5\u305a\u88dc\u52a9\u91d1\u306e\u5bfe\u8c61\u306b\u306a\u308a\u307e\u3059\u304b\uff1f<\/summary>\n<p>\u5fc5\u305a\u5bfe\u8c61\u306b\u306a\u308b\u3068\u306f\u9650\u308a\u307e\u305b\u3093\u3002\u5bfe\u8c61\u8005\u3001\u5bfe\u8c61\u7d4c\u8cbb\u3001\u767a\u6ce8\u6642\u671f\u3001\u4e8b\u696d\u8a08\u753b\u306e\u8981\u4ef6\u3092\u516c\u52df\u8981\u9818\u3067\u78ba\u8a8d\u3057\u3066\u304f\u3060\u3055\u3044\u3002<\/p>\n<\/details>\n<details>\n<summary>\u7533\u8acb\u524d\u306b\u4f55\u3092\u6e96\u5099\u3059\u308c\u3070\u3088\u3044\u3067\u3059\u304b\uff1f<\/summary>\n<p>\u4f1a\u793e\u60c5\u5831\u3001\u6295\u8cc7\u5185\u5bb9\u3001\u898b\u7a4d\u66f8\u3001\u8cc7\u91d1\u8a08\u753b\u3001\u5c0e\u5165\u5f8c\u306e\u52b9\u679c\u3092\u6574\u7406\u3057\u307e\u3059\u3002G\u30d3\u30baID\u3082\u65e9\u3081\u306b\u78ba\u8a8d\u3057\u307e\u3057\u3087\u3046\u3002<\/p>\n<\/details>\n<details>\n<summary>\u3069\u306e\u5236\u5ea6\u3092\u9078\u3079\u3070\u3088\u3044\u304b\u8ff7\u3063\u305f\u5834\u5408\u306f\uff1f<\/summary>\n<p>\u5730\u57df\u3001\u696d\u7a2e\u3001\u6295\u8cc7\u76ee\u7684\u3092\u5165\u529b\u3057\u3066\u5019\u88dc\u3092\u7d5e\u308b\u3068\u5224\u65ad\u3057\u3084\u3059\u304f\u306a\u308a\u307e\u3059\u3002\u7de0\u5207\u3068\u5bfe\u8c61\u7d4c\u8cbb\u304b\u3089\u512a\u5148\u9806\u4f4d\u3092\u4ed8\u3051\u307e\u3057\u3087\u3046\u3002<\/p>\n<\/details>\n<details>\n<summary>\u5ca9\u624b\u770c\u3067\u306f\u81ea\u6cbb\u4f53\u306e\u5236\u5ea6\u3082\u78ba\u8a8d\u3059\u3079\u304d\u3067\u3059\u304b\uff1f<\/summary>\n<p>\u5ca9\u624b\u770c\u306e\u90fd\u9053\u5e9c\u770c\u5236\u5ea6\u3060\u3051\u3067\u306a\u304f\u3001\u5e02\u533a\u753a\u6751\u3001\u5546\u5de5\u4f1a\u8b70\u6240\u3001\u7523\u696d\u632f\u8208\u6a5f\u95a2\u306e\u52df\u96c6\u3082\u78ba\u8a8d\u3057\u3066\u304f\u3060\u3055\u3044\u3002\u56fd\u306e\u5236\u5ea6\u3068\u4f75\u7528\u3067\u304d\u308b\u304b\u3082\u91cd\u8981\u3067\u3059\u3002<\/p>\n<\/details>\n<details>\n<summary>\u30af\u30ea\u30cb\u30c3\u30af\u3067\u7533\u8acb\u3059\u308b\u3068\u304d\u306b\u898b\u3089\u308c\u3084\u3059\u3044\u70b9\u306f\uff1f<\/summary>\n<p>\u533b\u7642\u30fb\u798f\u7949\u30fb\u4fdd\u80b2\u7cfb\u3067\u306f\u3001\u8a18\u9332\u696d\u52d9\u306e\u52b9\u7387\u5316\u3001\u4e88\u7d04\u30fb\u53d7\u4ed8\u3001\u8077\u54e1\u5b9a\u7740\u3001\u30b5\u30fc\u30d3\u30b9\u54c1\u8cea\u304c\u8ad6\u70b9\u306b\u306a\u308a\u3084\u3059\u3044\u3067\u3059\u3002 \u305d\u306e\u3046\u3048\u3067\u3001\u5bfe\u8c61\u7d4c\u8cbb\u3068\u5c0e\u5165\u5f8c\u306e\u52b9\u679c\u3092\u6570\u5b57\u3067\u8aac\u660e\u3067\u304d\u308b\u304b\u304c\u898b\u3089\u308c\u307e\u3059\u3002<\/p>\n<\/details>\n<\/div>\n<h2>\u6b21\u306b\u3084\u308b\u3053\u3068<\/h2>\n<p>\u6700\u5f8c\u306f\u3001\u9078\u3093\u3060\u5236\u5ea6\u3067\u672c\u5f53\u306b\u9032\u3081\u3089\u308c\u308b\u304b\u3092\u78ba\u304b\u3081\u307e\u3059\u3002<strong class=\"article-key-emphasis\"><u>\u516c\u52df\u8981\u9818<\/u><\/strong>\u3068\u306f\u3001\u52df\u96c6\u306e\u30eb\u30fc\u30eb\u306e\u3053\u3068\u3067\u3059\u3002\u898b\u7a4d\u66f8\u3001\u59cb\u3081\u308b\u65e5\u3001\u5fc5\u8981\u306a\u66f8\u985e\u3001\u7d42\u308f\u3063\u305f\u5f8c\u306e\u5831\u544a\u307e\u3067\u3001\u4e00\u3064\u306e\u6d41\u308c\u3067\u898b\u307e\u3057\u3087\u3046\u3002<\/p>\n<p>\u8ff7\u3063\u305f\u3068\u304d\u306f\u3001\u91d1\u984d\u304c\u3044\u3061\u3070\u3093\u5927\u304d\u3044\u5236\u5ea6\u304b\u3089\u9078\u3070\u306a\u304f\u3066\u3082\u5927\u4e08\u592b\u3067\u3059\u3002\u81ea\u793e\u306e\u56f0\u308a\u3054\u3068\u3001\u4f7f\u3046\u304a\u91d1\u3001\u7d42\u308f\u3063\u305f\u5f8c\u306e\u5909\u5316\u3092\u8aac\u660e\u3057\u3084\u3059\u3044\u5236\u5ea6\u304b\u3089\u898b\u76f4\u3057\u307e\u3057\u3087\u3046\u3002<\/p>\n<p>\u78ba\u8a8d\u30e1\u30e2\u306f\u3001\u3042\u3068\u3067\u76f8\u8ac7\u3059\u308b\u3068\u304d\u306b\u3082\u5f79\u7acb\u3061\u307e\u3059\u3002\u4f1a\u793e\u306e\u60c5\u5831\u3001\u4f7f\u3046\u304a\u91d1\u3001\u59cb\u3081\u305f\u3044\u6642\u671f\u3092\u4e00\u679a\u306b\u307e\u3068\u3081\u307e\u3059\u3002\u8a71\u304c\u65e9\u304f\u306a\u308a\u3001\u805e\u304d\u3082\u308c\u3082\u6e1b\u3089\u305b\u307e\u3059\u3002<\/p>\n<p>\u3059\u3050\u306b\u7533\u8acb\u3057\u306a\u3044\u5834\u5408\u3067\u3082\u3001\u6e96\u5099\u306f\u3080\u3060\u306b\u306a\u308a\u307e\u305b\u3093\u3002\u6b21\u306e\u52df\u96c6\u304c\u51fa\u305f\u3068\u304d\u3001\u524d\u306b\u4f5c\u3063\u305f\u30e1\u30e2\u3092\u76f4\u3059\u3060\u3051\u3067\u52d5\u304d\u51fa\u305b\u307e\u3059\u3002\u65e9\u3081\u306b\u5f62\u306b\u3057\u3066\u304a\u304f\u3053\u3068\u304c\u5927\u5207\u3067\u3059\u3002<\/p>\n<p>\u5236\u5ea6\u3092\u8abf\u3079\u305f\u65e5\u306f\u3001\u65e5\u4ed8\u3082\u66f8\u3044\u3066\u304f\u3060\u3055\u3044\u3002\u52df\u96c6\u306e\u5185\u5bb9\u306f\u5909\u308f\u308b\u3053\u3068\u304c\u3042\u308a\u307e\u3059\u3002\u3042\u3068\u3067\u898b\u76f4\u3059\u3068\u304d\u3001\u3069\u306e\u60c5\u5831\u3092\u898b\u305f\u304b\u5206\u304b\u308a\u307e\u3059\u3002<\/p>\n<p>\u6c17\u306b\u306a\u308b\u5236\u5ea6\u304c\u3042\u308c\u3070\u3001\u516c\u5f0f\u30da\u30fc\u30b8\u306e\u540d\u524d\u3082\u6b8b\u3057\u307e\u3057\u3087\u3046\u3002\u76f8\u8ac7\u5148\u306b\u898b\u305b\u308b\u3068\u3001\u8a71\u304c\u305a\u308c\u306b\u304f\u304f\u306a\u308a\u307e\u3059\u3002<\/p>\n<p>\u307e\u305a\u3001\u81ea\u793e\u306e\u6240\u5728\u5730\u3001\u696d\u7a2e\u3001<strong class=\"article-key-emphasis\"><u>\u5f93\u696d\u54e1\u6570<\/u><\/strong>\u3001\u4f7f\u3046\u4e88\u5b9a\u306e\u304a\u91d1\u3092\u66f8\u304d\u51fa\u3057\u307e\u3057\u3087\u3046\u3002\u5165\u308c\u305f\u3044\u8a2d\u5099\u3084\u30b5\u30fc\u30d3\u30b9\u3082\u66f8\u304d\u307e\u3059\u3002\u305d\u306e\u5f8c\u3067\u7121\u6599\u8a3a\u65ad\u3092\u4f7f\u3046\u3068\u3001\u5ca9\u624b\u770c \u30af\u30ea\u30cb\u30c3\u30af \u591a\u8a00\u8a9e\u5bfe\u5fdc \u88dc\u52a9\u91d1\u306b\u8fd1\u3044\u5019\u88dc\u3092\u898b\u3064\u3051\u3084\u3059\u304f\u306a\u308a\u307e\u3059\u3002<\/p>\n<p class=\"article-inline-cta\"><a href=\"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/matching\/\">\u4f7f\u3048\u308b\u88dc\u52a9\u91d1\u3092\u8a3a\u65ad<\/a><\/p>\n<p><!-- article-plan-hash: f3879044ec78e97aac9a8113acb4eb77f6363e568293cce61a461e4fed4002b3 --><br \/>\n<!-- image-brief-hash: 8e3c3248551fd30d7b76aea485adb65ff1c14a134e005745893ee7b0f95e3179 --><br \/>\n<!-- image-status: pending-image2 --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u5ca9\u624b\u770c\u306e\u30af\u30ea\u30cb\u30c3\u30af\u304c\u591a\u8a00\u8a9e\u5bfe\u5fdc\u306b\u4f7f\u3048\u308b\u88dc\u52a9\u91d1\u3002\u5bfe\u8c61\u306b\u306a\u308a\u3084\u3059\u3044\u5236\u5ea6\u3001\u7533\u8acb\u524d\u306e\u6e96\u5099\u3001\u7121\u6599\u8a3a\u65ad\u3067\u78ba\u8a8d\u3057\u305f\u3044\u30dd\u30a4\u30f3\u30c8\u3092\u89e3\u8aac\u3057\u307e\u3059\u3002<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[73],"tags":[40,39,74],"class_list":["post-206494","post","type-post","status-publish","format-standard","hentry","category-seo-61586a174c31e7a9b1728b7df5fccda2","tag-mofu","tag-39","tag-74"],"_links":{"self":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/posts\/206494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/comments?post=206494"}],"version-history":[{"count":1,"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/posts\/206494\/revisions"}],"predecessor-version":[{"id":216501,"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/posts\/206494\/revisions\/216501"}],"wp:attachment":[{"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/media?parent=206494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/categories?post=206494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/test.yumeno-marketing.jp\/test\/subsidy-matching\/wp-json\/wp\/v2\/tags?post=206494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}